{"id":748,"date":"2026-01-21T14:14:34","date_gmt":"2026-01-21T13:14:34","guid":{"rendered":"https:\/\/asmir.fr\/?p=748"},"modified":"2026-02-23T13:29:20","modified_gmt":"2026-02-23T12:29:20","slug":"02-01-26-galette-des-rois-asmir","status":"publish","type":"post","link":"https:\/\/asmir.fr\/index.php\/2026\/01\/21\/02-01-26-galette-des-rois-asmir\/","title":{"rendered":"Sainte Flaive des Loups &#8211; Galette des Rois ASMIR"},"content":{"rendered":"<p>En raison d&rsquo;une \u00e9pid\u00e9mie de grippe, la galette des Rois\u00a0 pr\u00e9vue \u00e0 la Marpa\u00a0 le lundi 11 janvier 2026 est annul\u00e9e.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En raison d&rsquo;une \u00e9pid\u00e9mie de grippe, la galette des Rois\u00a0 pr\u00e9vue \u00e0 la Marpa\u00a0 le lundi 11 janvier 2026 est annul\u00e9e.<\/p>\n","protected":false},"author":21,"featured_media":814,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-748","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"En raison d&#039;une \u00e9pid\u00e9mie de grippe, la galette des Rois pr\u00e9vue \u00e0 la Marpa le lundi 11 janvier 2026 est annul\u00e9e.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Joseph JOLLY\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/asmir.fr\/index.php\/2026\/01\/21\/02-01-26-galette-des-rois-asmir\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"ASMIR | Actions Solidaires en Milieu Rural - D\u00e9placement solidaire en Vend\u00e9e, Transport solidaire en Vend\u00e9e, Actions solidaires en Vend\u00e9e\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Sainte Flaive des Loups \u2013 Galette des Rois ASMIR - ASMIR | Actions Solidaires en Milieu Rural\" \/>\n\t\t<meta property=\"og:description\" content=\"En raison d&#039;une \u00e9pid\u00e9mie de grippe, la galette des Rois pr\u00e9vue \u00e0 la Marpa le lundi 11 janvier 2026 est annul\u00e9e.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/asmir.fr\/index.php\/2026\/01\/21\/02-01-26-galette-des-rois-asmir\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/asmir.fr\/wp-content\/uploads\/2022\/06\/asmir-logo-header.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/asmir.fr\/wp-content\/uploads\/2022\/06\/asmir-logo-header.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"214\" \/>\n\t\t<meta property=\"og:image:height\" content=\"255\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-01-21T13:14:34+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-02-23T12:29:20+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Sainte Flaive des Loups \u2013 Galette des Rois ASMIR - ASMIR | Actions Solidaires en Milieu Rural\" \/>\n\t\t<meta name=\"twitter:description\" content=\"En raison d&#039;une \u00e9pid\u00e9mie de grippe, la galette des Rois pr\u00e9vue \u00e0 la Marpa le lundi 11 janvier 2026 est annul\u00e9e.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/asmir.fr\/wp-content\/uploads\/2022\/06\/asmir-logo-header.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/asmir.fr\\\/index.php\\\/2026\\\/01\\\/21\\\/02-01-26-galette-des-rois-asmir\\\/#blogposting\",\"name\":\"Sainte Flaive des Loups \\u2013 Galette des Rois ASMIR - ASMIR | Actions Solidaires en Milieu Rural\",\"headline\":\"Sainte Flaive des Loups &#8211; Galette des Rois ASMIR\",\"author\":{\"@id\":\"https:\\\/\\\/asmir.fr\\\/index.php\\\/author\\\/joseph-jolly\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/asmir.fr\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/asmir.fr\\\/wp-content\\\/uploads\\\/galettegirouard-1.jpg\",\"width\":422,\"height\":237},\"datePublished\":\"2026-01-21T14:14:34+01:00\",\"dateModified\":\"2026-02-23T13:29:20+01:00\",\"inLanguage\":\"fr-FR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/asmir.fr\\\/index.php\\\/2026\\\/01\\\/21\\\/02-01-26-galette-des-rois-asmir\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/asmir.fr\\\/index.php\\\/2026\\\/01\\\/21\\\/02-01-26-galette-des-rois-asmir\\\/#webpage\"},\"articleSection\":\"Actualit\\u00e9s\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/asmir.fr\\\/index.php\\\/2026\\\/01\\\/21\\\/02-01-26-galette-des-rois-asmir\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/asmir.fr#listItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/asmir.fr\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/asmir.fr\\\/index.php\\\/category\\\/actualite\\\/#listItem\",\"name\":\"Actualit\\u00e9s\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/asmir.fr\\\/index.php\\\/category\\\/actualite\\\/#listItem\",\"position\":2,\"name\":\"Actualit\\u00e9s\",\"item\":\"https:\\\/\\\/asmir.fr\\\/index.php\\\/category\\\/actualite\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/asmir.fr\\\/index.php\\\/2026\\\/01\\\/21\\\/02-01-26-galette-des-rois-asmir\\\/#listItem\",\"name\":\"Sainte Flaive des Loups &#8211; Galette des Rois ASMIR\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/asmir.fr#listItem\",\"name\":\"Accueil\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/asmir.fr\\\/index.php\\\/2026\\\/01\\\/21\\\/02-01-26-galette-des-rois-asmir\\\/#listItem\",\"position\":3,\"name\":\"Sainte Flaive des Loups &#8211; Galette des Rois ASMIR\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/asmir.fr\\\/index.php\\\/category\\\/actualite\\\/#listItem\",\"name\":\"Actualit\\u00e9s\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/asmir.fr\\\/#organization\",\"name\":\"ASMIR | Actions Solidaires en Milieu Rural\",\"description\":\"D\\u00e9placement solidaire en Vend\\u00e9e, Transport solidaire en Vend\\u00e9e, Actions solidaires en Vend\\u00e9e\",\"url\":\"https:\\\/\\\/asmir.fr\\\/\",\"telephone\":\"+33687942920\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/asmir.fr\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/asmir-logo-header.png\",\"@id\":\"https:\\\/\\\/asmir.fr\\\/index.php\\\/2026\\\/01\\\/21\\\/02-01-26-galette-des-rois-asmir\\\/#organizationLogo\",\"width\":214,\"height\":255},\"image\":{\"@id\":\"https:\\\/\\\/asmir.fr\\\/index.php\\\/2026\\\/01\\\/21\\\/02-01-26-galette-des-rois-asmir\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/asmir.fr\\\/index.php\\\/author\\\/joseph-jolly\\\/#author\",\"url\":\"https:\\\/\\\/asmir.fr\\\/index.php\\\/author\\\/joseph-jolly\\\/\",\"name\":\"Joseph JOLLY\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/asmir.fr\\\/index.php\\\/2026\\\/01\\\/21\\\/02-01-26-galette-des-rois-asmir\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4dd0d9040745c1f104f1db4e1c37db375000282abf29a8fed429d863f78f0e84?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Joseph JOLLY\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/asmir.fr\\\/index.php\\\/2026\\\/01\\\/21\\\/02-01-26-galette-des-rois-asmir\\\/#webpage\",\"url\":\"https:\\\/\\\/asmir.fr\\\/index.php\\\/2026\\\/01\\\/21\\\/02-01-26-galette-des-rois-asmir\\\/\",\"name\":\"Sainte Flaive des Loups \\u2013 Galette des Rois ASMIR - ASMIR | Actions Solidaires en Milieu Rural\",\"description\":\"En raison d'une \\u00e9pid\\u00e9mie de grippe, la galette des Rois pr\\u00e9vue \\u00e0 la Marpa le lundi 11 janvier 2026 est annul\\u00e9e.\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/asmir.fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/asmir.fr\\\/index.php\\\/2026\\\/01\\\/21\\\/02-01-26-galette-des-rois-asmir\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/asmir.fr\\\/index.php\\\/author\\\/joseph-jolly\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/asmir.fr\\\/index.php\\\/author\\\/joseph-jolly\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/asmir.fr\\\/wp-content\\\/uploads\\\/galettegirouard-1.jpg\",\"@id\":\"https:\\\/\\\/asmir.fr\\\/index.php\\\/2026\\\/01\\\/21\\\/02-01-26-galette-des-rois-asmir\\\/#mainImage\",\"width\":422,\"height\":237},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/asmir.fr\\\/index.php\\\/2026\\\/01\\\/21\\\/02-01-26-galette-des-rois-asmir\\\/#mainImage\"},\"datePublished\":\"2026-01-21T14:14:34+01:00\",\"dateModified\":\"2026-02-23T13:29:20+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/asmir.fr\\\/#website\",\"url\":\"https:\\\/\\\/asmir.fr\\\/\",\"name\":\"ASMIR | Actions Solidaires en Milieu Rural\",\"description\":\"D\\u00e9placement solidaire en Vend\\u00e9e, Transport solidaire en Vend\\u00e9e, Actions solidaires en Vend\\u00e9e\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/asmir.fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Sainte Flaive des Loups \u2013 Galette des Rois ASMIR - ASMIR | Actions Solidaires en Milieu Rural","description":"En raison d'une \u00e9pid\u00e9mie de grippe, la galette des Rois pr\u00e9vue \u00e0 la Marpa le lundi 11 janvier 2026 est annul\u00e9e.","canonical_url":"https:\/\/asmir.fr\/index.php\/2026\/01\/21\/02-01-26-galette-des-rois-asmir\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/asmir.fr\/index.php\/2026\/01\/21\/02-01-26-galette-des-rois-asmir\/#blogposting","name":"Sainte Flaive des Loups \u2013 Galette des Rois ASMIR - ASMIR | Actions Solidaires en Milieu Rural","headline":"Sainte Flaive des Loups &#8211; Galette des Rois ASMIR","author":{"@id":"https:\/\/asmir.fr\/index.php\/author\/joseph-jolly\/#author"},"publisher":{"@id":"https:\/\/asmir.fr\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/asmir.fr\/wp-content\/uploads\/galettegirouard-1.jpg","width":422,"height":237},"datePublished":"2026-01-21T14:14:34+01:00","dateModified":"2026-02-23T13:29:20+01:00","inLanguage":"fr-FR","mainEntityOfPage":{"@id":"https:\/\/asmir.fr\/index.php\/2026\/01\/21\/02-01-26-galette-des-rois-asmir\/#webpage"},"isPartOf":{"@id":"https:\/\/asmir.fr\/index.php\/2026\/01\/21\/02-01-26-galette-des-rois-asmir\/#webpage"},"articleSection":"Actualit\u00e9s"},{"@type":"BreadcrumbList","@id":"https:\/\/asmir.fr\/index.php\/2026\/01\/21\/02-01-26-galette-des-rois-asmir\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/asmir.fr#listItem","position":1,"name":"Accueil","item":"https:\/\/asmir.fr","nextItem":{"@type":"ListItem","@id":"https:\/\/asmir.fr\/index.php\/category\/actualite\/#listItem","name":"Actualit\u00e9s"}},{"@type":"ListItem","@id":"https:\/\/asmir.fr\/index.php\/category\/actualite\/#listItem","position":2,"name":"Actualit\u00e9s","item":"https:\/\/asmir.fr\/index.php\/category\/actualite\/","nextItem":{"@type":"ListItem","@id":"https:\/\/asmir.fr\/index.php\/2026\/01\/21\/02-01-26-galette-des-rois-asmir\/#listItem","name":"Sainte Flaive des Loups &#8211; Galette des Rois ASMIR"},"previousItem":{"@type":"ListItem","@id":"https:\/\/asmir.fr#listItem","name":"Accueil"}},{"@type":"ListItem","@id":"https:\/\/asmir.fr\/index.php\/2026\/01\/21\/02-01-26-galette-des-rois-asmir\/#listItem","position":3,"name":"Sainte Flaive des Loups &#8211; Galette des Rois ASMIR","previousItem":{"@type":"ListItem","@id":"https:\/\/asmir.fr\/index.php\/category\/actualite\/#listItem","name":"Actualit\u00e9s"}}]},{"@type":"Organization","@id":"https:\/\/asmir.fr\/#organization","name":"ASMIR | Actions Solidaires en Milieu Rural","description":"D\u00e9placement solidaire en Vend\u00e9e, Transport solidaire en Vend\u00e9e, Actions solidaires en Vend\u00e9e","url":"https:\/\/asmir.fr\/","telephone":"+33687942920","logo":{"@type":"ImageObject","url":"https:\/\/asmir.fr\/wp-content\/uploads\/2022\/06\/asmir-logo-header.png","@id":"https:\/\/asmir.fr\/index.php\/2026\/01\/21\/02-01-26-galette-des-rois-asmir\/#organizationLogo","width":214,"height":255},"image":{"@id":"https:\/\/asmir.fr\/index.php\/2026\/01\/21\/02-01-26-galette-des-rois-asmir\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/asmir.fr\/index.php\/author\/joseph-jolly\/#author","url":"https:\/\/asmir.fr\/index.php\/author\/joseph-jolly\/","name":"Joseph JOLLY","image":{"@type":"ImageObject","@id":"https:\/\/asmir.fr\/index.php\/2026\/01\/21\/02-01-26-galette-des-rois-asmir\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4dd0d9040745c1f104f1db4e1c37db375000282abf29a8fed429d863f78f0e84?s=96&d=mm&r=g","width":96,"height":96,"caption":"Joseph JOLLY"}},{"@type":"WebPage","@id":"https:\/\/asmir.fr\/index.php\/2026\/01\/21\/02-01-26-galette-des-rois-asmir\/#webpage","url":"https:\/\/asmir.fr\/index.php\/2026\/01\/21\/02-01-26-galette-des-rois-asmir\/","name":"Sainte Flaive des Loups \u2013 Galette des Rois ASMIR - ASMIR | Actions Solidaires en Milieu Rural","description":"En raison d'une \u00e9pid\u00e9mie de grippe, la galette des Rois pr\u00e9vue \u00e0 la Marpa le lundi 11 janvier 2026 est annul\u00e9e.","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/asmir.fr\/#website"},"breadcrumb":{"@id":"https:\/\/asmir.fr\/index.php\/2026\/01\/21\/02-01-26-galette-des-rois-asmir\/#breadcrumblist"},"author":{"@id":"https:\/\/asmir.fr\/index.php\/author\/joseph-jolly\/#author"},"creator":{"@id":"https:\/\/asmir.fr\/index.php\/author\/joseph-jolly\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/asmir.fr\/wp-content\/uploads\/galettegirouard-1.jpg","@id":"https:\/\/asmir.fr\/index.php\/2026\/01\/21\/02-01-26-galette-des-rois-asmir\/#mainImage","width":422,"height":237},"primaryImageOfPage":{"@id":"https:\/\/asmir.fr\/index.php\/2026\/01\/21\/02-01-26-galette-des-rois-asmir\/#mainImage"},"datePublished":"2026-01-21T14:14:34+01:00","dateModified":"2026-02-23T13:29:20+01:00"},{"@type":"WebSite","@id":"https:\/\/asmir.fr\/#website","url":"https:\/\/asmir.fr\/","name":"ASMIR | Actions Solidaires en Milieu Rural","description":"D\u00e9placement solidaire en Vend\u00e9e, Transport solidaire en Vend\u00e9e, Actions solidaires en Vend\u00e9e","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/asmir.fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"ASMIR | Actions Solidaires en Milieu Rural - D\u00e9placement solidaire en Vend\u00e9e, Transport solidaire en Vend\u00e9e, Actions solidaires en Vend\u00e9e","og:type":"article","og:title":"Sainte Flaive des Loups \u2013 Galette des Rois ASMIR - ASMIR | Actions Solidaires en Milieu Rural","og:description":"En raison d'une \u00e9pid\u00e9mie de grippe, la galette des Rois pr\u00e9vue \u00e0 la Marpa le lundi 11 janvier 2026 est annul\u00e9e.","og:url":"https:\/\/asmir.fr\/index.php\/2026\/01\/21\/02-01-26-galette-des-rois-asmir\/","og:image":"https:\/\/asmir.fr\/wp-content\/uploads\/2022\/06\/asmir-logo-header.png","og:image:secure_url":"https:\/\/asmir.fr\/wp-content\/uploads\/2022\/06\/asmir-logo-header.png","og:image:width":214,"og:image:height":255,"article:published_time":"2026-01-21T13:14:34+00:00","article:modified_time":"2026-02-23T12:29:20+00:00","twitter:card":"summary_large_image","twitter:title":"Sainte Flaive des Loups \u2013 Galette des Rois ASMIR - ASMIR | Actions Solidaires en Milieu Rural","twitter:description":"En raison d'une \u00e9pid\u00e9mie de grippe, la galette des Rois pr\u00e9vue \u00e0 la Marpa le lundi 11 janvier 2026 est annul\u00e9e.","twitter:image":"https:\/\/asmir.fr\/wp-content\/uploads\/2022\/06\/asmir-logo-header.png"},"aioseo_meta_data":{"post_id":"748","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2024-01-15 17:59:31","updated":"2026-02-23 12:39:09","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/asmir.fr\" title=\"Accueil\">Accueil<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/asmir.fr\/index.php\/category\/actualite\/\" title=\"Actualit\u00e9s\">Actualit\u00e9s<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSainte Flaive des Loups \u2013 Galette des Rois ASMIR\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Accueil","link":"https:\/\/asmir.fr"},{"label":"Actualit\u00e9s","link":"https:\/\/asmir.fr\/index.php\/category\/actualite\/"},{"label":"Sainte Flaive des Loups &#8211; Galette des Rois ASMIR","link":"https:\/\/asmir.fr\/index.php\/2026\/01\/21\/02-01-26-galette-des-rois-asmir\/"}],"_links":{"self":[{"href":"https:\/\/asmir.fr\/index.php\/wp-json\/wp\/v2\/posts\/748","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/asmir.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/asmir.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/asmir.fr\/index.php\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/asmir.fr\/index.php\/wp-json\/wp\/v2\/comments?post=748"}],"version-history":[{"count":4,"href":"https:\/\/asmir.fr\/index.php\/wp-json\/wp\/v2\/posts\/748\/revisions"}],"predecessor-version":[{"id":786,"href":"https:\/\/asmir.fr\/index.php\/wp-json\/wp\/v2\/posts\/748\/revisions\/786"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/asmir.fr\/index.php\/wp-json\/wp\/v2\/media\/814"}],"wp:attachment":[{"href":"https:\/\/asmir.fr\/index.php\/wp-json\/wp\/v2\/media?parent=748"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/asmir.fr\/index.php\/wp-json\/wp\/v2\/categories?post=748"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/asmir.fr\/index.php\/wp-json\/wp\/v2\/tags?post=748"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}